{"id":272,"date":"2024-07-29T13:35:07","date_gmt":"2024-07-29T13:35:07","guid":{"rendered":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/?p=272"},"modified":"2024-07-29T13:53:17","modified_gmt":"2024-07-29T13:53:17","slug":"wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024","status":"publish","type":"post","link":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/","title":{"rendered":"W\u00fcrde und Solidarit\u00e4t &#8211; Austausch und Diskussion mit Dr. Holger Thiel am 15. April 2024"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Ankn\u00fcpfungspunkte zu unseren bisherigen zwei Veranstaltungen zu W\u00fcrde und Solidarit\u00e4t am 28.8.2023 und 29.1.2024<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>Mensch und Natur:<\/u><\/strong> &nbsp;Wir haben uns in den vorangegangenen zwei Veranstaltungen der W\u00fcrde des Menschen angen\u00e4hert, indem wir die \u201eNicht-Verdinglichung des Menschen und der Natur\u201c als eine wichtige Voraussetzung herausgestellt haben, die wertsch\u00e4tzende Handlungen zur Folge haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>Wie kann eine wertsch\u00e4tzende Haltung entstehen?<\/u><\/strong> &nbsp;Wenn es gelingt, den Menschen unabh\u00e4ngig von Wertvorstellungen als an sich wertvoll zu erkennen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Weiterf\u00fchrende Gedanken, Impulse und Fragen im dialogischen Gespr\u00e4ch am 15.4.2024<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>Wertsch\u00e4tzung durch Begegnung:<\/u><\/strong> &nbsp;Der historische Liebesroman von Martin Walzer \u00fcber den 73j\u00e4hrigen Goethe und die 19j\u00e4hrige Ulrike von Levetzow (Romantitel: Ein liebender Mann) kann als gelungener Versuch bezeichnet werden, sich der Perspektive Goethes zu n\u00e4hern, ohne ihn zu instrumentalisieren. Die aufrichtig empfundene Liebe Goethes zu Ulrike von Levetzow wird von Walser literarisch so beschrieben, dass eine aufrichtige tiefe Liebe zum Vorschein kommt, ohne den bekannten gesellschaftlichen Bewertungen hinsichtlich des gro\u00dfen Altersunterschiedes nachzugehen. Walzer, ein \u201eGoethe-Verehrer\u201c, l\u00e4sst im Roman die Natur und ihre Erhabenheit sowie die Liebe zwischen den zwei Liebenden so sein, wie sie ist. Der Roman kann hier als k\u00fcnstlerische Wertsch\u00e4tzung Walsers gegen\u00fcber Goethe verstanden werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Einen anderen Menschen wertzusch\u00e4tzen, ihn zu w\u00fcrdigen kann entstehen, wenn wir erkennen, was diese Begegnung bei uns ausgel\u00f6st hat. Je weniger wir \u00fcber andere Menschen urteilen, sie bewerten und zum Objekt machen, desto eher kann sich wertsch\u00e4tzendes Handeln bemerkbar machen. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>Begegnungen \u2013 Erwartungen \u2013 Bewertungen &#8211; Werte:<\/u><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Begegnungen zwischen Menschen<\/strong> k\u00f6nnen auf der einen Seite wohltuend, inspirierend und zur eigenen Entfaltung beitragen auf der anderen Seite Vorbehalte und Erwartungshaltungen festigen. <strong>Begegnungen eines Menschen mit der Natur<\/strong> \u2013 beispielsweise mit einem Baum \u2013 k\u00f6nnen einem Menschen hilfreiche Impulse geben und seine Gef\u00fchlsbereiche neu anregen, zum Beispiel beruhigend wirken, Freude und Dankbarkeit empfinden lassen, neue Zuversicht und Vertrauen entdecken, Zufriedenheit empfinden k\u00f6nnen \u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Erwartungen an andere Menschen<\/strong> sind \u2013 bewusst oder unbewusst \u2013 von Vorurteilen, Vorbehalten, verzerrten Wahrnehmungen und einem \u201enaturhaften\u201c Zwang gekennzeichnet, andere Menschen sowie die jeweilige Lebenssituation mit den jeweiligen Akteuren und Objektkonstellationen einzusch\u00e4tzen und zu bewerten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Schul-P\u00e4dagogik geht es u.a. darum, Kindern <strong>Werte<\/strong> zu vermitteln, die ihnen helfen, sich in der bestehenden sozialen Welt zurechtzufinden. K\u00f6nnen die von Natur aus neugierigen Kinder so auf ihrem Lebensweg begleitet werden, dass ihre jeweiligen Grundbed\u00fcrfnisse auch in der Schule Beachtung finden?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im <strong>ZEN-Buddhismus<\/strong> kommt der Lebensf\u00fchrung im Hier und Jetzt gro\u00dfe Bedeutung zu. Alle Dinge, Lebewesen und Ereignisse werden als Einheit angesehen und somit gleich gewichtet. Das so entstehende reine SEIN soll f\u00fcr den Menschen befreiend sein und das neugierige Lernen f\u00f6rdern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Blick auf die letzten Jahrhunderte der Menschheitsgeschichte zeigt, dass das <strong>Denken in Zwecken<\/strong> mit dazu gef\u00fchrt hat, dass vielf\u00e4ltigste Erfindungen und naturwissenschaftliche Forschungen (wie z.B.: Fortschritte bei der Bek\u00e4mpfung von Krankheiten und Seuchen, Entwicklung von Maschinen, die die Arbeit von Menschen erleichtern, Elektrizit\u00e4t, Eisenbahn, Automobile, Telefon, Funk, Computer, Internet uvam.) das menschliche Leben stark ver\u00e4ndert hat. Neben den nicht zu leugnenden Fortschritten, beispielsweise im Medizinbereich oder bei der Produktion von Massenwaren in einer automatisierten Fertigungsanlage, sind neue negative Auswirkungen entstanden, wie beispielsweise die Ausbeutung von Fabrikarbeitern, gro\u00dfe soziale Probleme durch Landflucht, Zerst\u00f6rung von sozialen Beziehungen uvam. Um den negativen Auswirkungen entgegenzuwirken entstanden Gewerkschaftsorganisationen und eine Sozialgesetzgebung, die versuchte, die besonderen Risiken, wie Arbeitsunf\u00e4lle, Altersarmut, Krankheiten, Arbeitslosigkeit durch spezifische Leistungen zu minimieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wirkung von Begegnung am Beispiel des Schriftstellers Albert Camus und der Schauspielerin Maria Casar\u00e8s: <\/strong>Charles P\u00e9pin, der Autor des Buches \u201eKleine Philosophie der Begegnung\u201c (2022) beschreibt, wie eine allt\u00e4gliche Begegnung zwischen dem Schriftsteller Albert Camus (1913-1960) und der Schauspielerin Maria Casar\u00e8s (1922-1996) dazu f\u00fchrte, dass sich Camus Lebenseinstellungen grundlegend ver\u00e4nderten und eine zw\u00f6lfj\u00e4hrige intensive Liebesbeziehung mit \u00fcber 500 Briefen entstand. Aus dieser Liebe, aus dieser Freundschaft entstanden Kr\u00e4fte zu grundlegenden Einstellungs\u00e4nderungen.&nbsp; Zitat von Seite 79: \u201eDer geliebte Mensch kann auch unser Freund im aristotelischen Sinne sein. Camus erkannte, dass er durch seine Begegnung mit Maria gewachsen war, stolzer auf sein Leben sein konnte, weniger schnell in Selbsthass verfiel, offener war f\u00fcr Bewunderung. Diese bejahende Kraft schlummerte in ihm, aber erst die Begegnung mit ihr hat es ihm erm\u00f6glicht, in den Worten von Aristoteles, &lt; diese Anlage zu aktualisieren &gt;. Er hat sich nicht nur f\u00fcr Marias Weltsicht ge\u00f6ffnet, sondern auch seine eigene weiterentwickelt. Wenn wir uns durch die Ber\u00fchrung mit anderen ver\u00e4ndern, begreifen wir, wie sehr wir sie brauchen, um wir selbst zu werden.\u201c &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Frage: Wie w\u00e4re es, wenn wir jede Begegnung als eine potentielle Freundschaft betrachten k\u00f6nnten?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a><strong><u>Kritische Theorie \u2013 Komplexit\u00e4t und Vielfalt &#8211; Br\u00fccke zur Solidarit\u00e4t:<\/u><\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Kritische Theorie der Frankfurter Schule wurde in der ersten H\u00e4lfte des 20. Jahrhunderts durch den Sozialphilosophen Max Horkheimer (1895-1973), den Philosophen und Soziologen Theodor W. Adorno (1903-1969) und den Philosophen und Soziologen Herbert Marcuse (1898-1979) begr\u00fcndet. Die Kritische Theorie kritisiert fundamental die b\u00fcrgerlich-kapitalistische Gesellschaft mit ihren Herrschafts- und Unterdr\u00fcckungsmechanismen. Sie beschreibt und analysiert beispielsweise soziale Ungerechtigkeiten, die Entstehung des Faschismus und die Krisen des Kapitalismus, \u201e \u2026 mit dem Ziel einer vern\u00fcnftigen Gesellschaft m\u00fcndiger Menschen \u2013 Menschen, die bereit und f\u00e4hig sein k\u00f6nnen zur Selbstbestimmung, Unabh\u00e4ngigkeit und Eigenst\u00e4ndigkeit\u201c (nach Hobmair, Soziologie, 2019, Seiten 224-225). <strong>Marcuse<\/strong> weist am Beispiel der Nazi-Ideologie darauf hin, dass Solidarit\u00e4t bei oberfl\u00e4chlicher Anwendung in einem autorit\u00e4ren Herrschaftssystem zu menschenverachtenden negativen Auswirkungen f\u00fchren kann. Beispiel: Solidarit\u00e4t von Mitgliedern innerhalb von Nazi-Organisationen, die Andersdenkende bek\u00e4mpfen, erniedrigen, ausschlie\u00dfen oder als lebensunwert bezeichnen und umbringen. Zudem werden gesellschaftliche Grundprobleme wie die gerechte Verteilung und Teilhabe aller Menschen (Problem: Arm und Reich bzw. die Entwicklung zu einer Zwei-Drittel-Gesellschaft) verdeckt. <strong>Adorno<\/strong> beschreibt Solidarit\u00e4t u.a. als sch\u00f6ner Schein, der nicht erzwungen werden kann und eher utopischen Charakter hat. Seine Solidarit\u00e4t-Utopie umschreibt er mit den Worten: gleich \u2013 gleich (Gleichheit aller Menschen und Teil der Welt sein); \u201ewir sind gleich\u201c ist die solidarische Grundhaltung; offen sein gegen\u00fcber dem Unbekannten; den anderen erst einmal so sein zu lassen wie er\/sie ist; es gibt eine Subjektivit\u00e4t und ein Eigeninteresse; Begegnung hei\u00dft, sich dem Anderen anzun\u00e4hern; es ist nicht einfach, die Komplexit\u00e4t jedes Einzelnen mit der Vielfalt der gesamten nat\u00fcrlichen Welt zu verstehen und zu leben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>Grundlagen und Thesen zur Solidarit\u00e4t:<\/u><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Begriffliches<\/strong>: &nbsp;solidarisch (lat. solidus; solide); Solidarit\u00e4t: unbedingtes Zusammenhalten mit jemandem aufgrund gleicher Anschauungen und Ziele; Zusammenhalt zwischen gleichgesinnten oder gleichgestellten Individuen, Gruppen, Gemeinschaften und V\u00f6lkern; Solidarit\u00e4t bekommt je nach Weltanschauung einen anderen Sinn; Solidarit\u00e4t ist die Suche nach gemeinsamen \u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>These<\/strong>: Solidarit\u00e4t ist kein Wert an sich. Solidarit\u00e4t steht immer im Kontext der Zeit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Beispiel Familie<\/strong>: In Familien dominiert im Regelfall die Haltung der Verbundenheit und die Unterst\u00fctzung von Ideen, Aktivit\u00e4ten und Zielen anderer Familienmitglieder. Kritik bedeutet in diesem Kontext zun\u00e4chst, dass man etwas ver\u00e4ndern will \u2013 ohne die Solidarit\u00e4t, die Verbundenheit mit dem anderen aufzugeben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>These:<\/strong> Verst\u00e4ndigung ist die Basis von Solidarit\u00e4t.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Verst\u00e4ndigung<\/strong>: den anderen nicht ausnutzen zu wollen; sich verbunden f\u00fchlen mit \u2026; eine wertsch\u00e4tzende Verst\u00e4ndigung im Alltag praktizieren;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Frage<\/strong>: Was sind unsere Leitplanken der Solidarit\u00e4t?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Meine kurze Zusammenfassung \u2013 aus der Ich-Perspektive<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mich hat das dialogische Gespr\u00e4ch mit Holger Thiel und allen Teilnehmenden diesmal wieder wohltuend angeregt, mich weiter mit Gespr\u00e4chsimpulsen zu \u201eWertsch\u00e4tzung durch Begegnung\u201c, Erwartungen, Wirkungen von Begegnungen, ZEN-Buddhismus vs&nbsp; Denken in Zwecken sowie Solidarit\u00e4t und Kritische Theorie zu besch\u00e4ftigen. Beeindruckt hat mich wieder einmal, dass unsere Gespr\u00e4che von Achtung, Respekt und Wohlwollendem Zuh\u00f6ren gepr\u00e4gt waren. Ich habe mich sehr wohl gef\u00fchlt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Berlin, 29.7.2024 \/ Otto Hofmann<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">PS: Meine nachtr\u00e4gliche Entdeckung: \u201eDie W\u00fcrde der Natur achten\u201c \u2013 WDR-Podcast vom 6.5.2024 mit Umweltethiker Eckart L\u00f6hr &#8211; &nbsp;ca. 55 Min. \u2013 Philosophisches Radio \u2013 Link: &nbsp;<a href=\"https:\/\/www.ardaudiothek.de\/episode\/wdr-5-das-philosophische-radio\/eckart-loehr-die-wuerde-der-natur-achten\/wdr-5\/13378747\/\">https:\/\/www.ardaudiothek.de\/episode\/wdr-5-das-philosophische-radio\/eckart-loehr-die-wuerde-der-natur-achten\/wdr-5\/13378747\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ankn\u00fcpfungspunkte zu unseren bisherigen zwei Veranstaltungen zu W\u00fcrde und Solidarit\u00e4t am 28.8.2023 und 29.1.2024 Mensch und Natur: &nbsp;Wir haben uns in den vorangegangenen zwei Veranstaltungen der W\u00fcrde des Menschen angen\u00e4hert, indem wir die \u201eNicht-Verdinglichung des Menschen und der Natur\u201c als eine wichtige Voraussetzung herausgestellt haben, die wertsch\u00e4tzende Handlungen zur Folge haben. Wie kann eine wertsch\u00e4tzende&hellip;<\/p>\n","protected":false},"author":2,"featured_media":268,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[11,10],"class_list":["post-272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veranstaltung","tag-solidaritaet","tag-wuerde"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>W\u00fcrde und Solidarit\u00e4t - Austausch und Diskussion mit Dr. Holger Thiel am 15. April 2024 - W\u00fcrdekompass-Berlin-Britz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"W\u00fcrde und Solidarit\u00e4t - Austausch und Diskussion mit Dr. Holger Thiel am 15. April 2024 - W\u00fcrdekompass-Berlin-Britz\" \/>\n<meta property=\"og:description\" content=\"Ankn\u00fcpfungspunkte zu unseren bisherigen zwei Veranstaltungen zu W\u00fcrde und Solidarit\u00e4t am 28.8.2023 und 29.1.2024 Mensch und Natur: &nbsp;Wir haben uns in den vorangegangenen zwei Veranstaltungen der W\u00fcrde des Menschen angen\u00e4hert, indem wir die \u201eNicht-Verdinglichung des Menschen und der Natur\u201c als eine wichtige Voraussetzung herausgestellt haben, die wertsch\u00e4tzende Handlungen zur Folge haben. Wie kann eine wertsch\u00e4tzende&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"W\u00fcrdekompass-Berlin-Britz\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-29T13:35:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-29T13:53:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/wp-content\/uploads\/2024\/07\/Solidaritaet_I.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1748\" \/>\n\t<meta property=\"og:image:height\" content=\"1240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Barbara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Barbara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/index.php\\\/2024\\\/07\\\/29\\\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/index.php\\\/2024\\\/07\\\/29\\\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\\\/\"},\"author\":{\"name\":\"Barbara\",\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/#\\\/schema\\\/person\\\/3350a37c9cd83c4675191c961d7074aa\"},\"headline\":\"W\u00fcrde und Solidarit\u00e4t &#8211; Austausch und Diskussion mit Dr. Holger Thiel am 15. April 2024\",\"datePublished\":\"2024-07-29T13:35:07+00:00\",\"dateModified\":\"2024-07-29T13:53:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/index.php\\\/2024\\\/07\\\/29\\\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\\\/\"},\"wordCount\":1350,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/index.php\\\/2024\\\/07\\\/29\\\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Solidaritaet_I.jpg\",\"keywords\":[\"Solidarit\u00e4t\",\"W\u00fcrde\"],\"articleSection\":[\"Veranstaltung\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/index.php\\\/2024\\\/07\\\/29\\\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/index.php\\\/2024\\\/07\\\/29\\\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\\\/\",\"url\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/index.php\\\/2024\\\/07\\\/29\\\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\\\/\",\"name\":\"W\u00fcrde und Solidarit\u00e4t - Austausch und Diskussion mit Dr. Holger Thiel am 15. April 2024 - W\u00fcrdekompass-Berlin-Britz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/index.php\\\/2024\\\/07\\\/29\\\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/index.php\\\/2024\\\/07\\\/29\\\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Solidaritaet_I.jpg\",\"datePublished\":\"2024-07-29T13:35:07+00:00\",\"dateModified\":\"2024-07-29T13:53:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/#\\\/schema\\\/person\\\/3350a37c9cd83c4675191c961d7074aa\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/index.php\\\/2024\\\/07\\\/29\\\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/index.php\\\/2024\\\/07\\\/29\\\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/index.php\\\/2024\\\/07\\\/29\\\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Solidaritaet_I.jpg\",\"contentUrl\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Solidaritaet_I.jpg\",\"width\":1748,\"height\":1240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/index.php\\\/2024\\\/07\\\/29\\\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"W\u00fcrde und Solidarit\u00e4t &#8211; Austausch und Diskussion mit Dr. Holger Thiel am 15. April 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/#website\",\"url\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/\",\"name\":\"W\u00fcrdekompass-Berlin-Britz\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/#\\\/schema\\\/person\\\/3350a37c9cd83c4675191c961d7074aa\",\"name\":\"Barbara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32193af0f2e1388eb6828af0dfdad4af2a8fe7eb79ad44cf5b73e6840c7980ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32193af0f2e1388eb6828af0dfdad4af2a8fe7eb79ad44cf5b73e6840c7980ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32193af0f2e1388eb6828af0dfdad4af2a8fe7eb79ad44cf5b73e6840c7980ed?s=96&d=mm&r=g\",\"caption\":\"Barbara\"},\"url\":\"https:\\\/\\\/berlin-britz.xn--wrdekompass-thb.org\\\/index.php\\\/author\\\/barbara\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"W\u00fcrde und Solidarit\u00e4t - Austausch und Diskussion mit Dr. Holger Thiel am 15. April 2024 - W\u00fcrdekompass-Berlin-Britz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/","og_locale":"de_DE","og_type":"article","og_title":"W\u00fcrde und Solidarit\u00e4t - Austausch und Diskussion mit Dr. Holger Thiel am 15. April 2024 - W\u00fcrdekompass-Berlin-Britz","og_description":"Ankn\u00fcpfungspunkte zu unseren bisherigen zwei Veranstaltungen zu W\u00fcrde und Solidarit\u00e4t am 28.8.2023 und 29.1.2024 Mensch und Natur: &nbsp;Wir haben uns in den vorangegangenen zwei Veranstaltungen der W\u00fcrde des Menschen angen\u00e4hert, indem wir die \u201eNicht-Verdinglichung des Menschen und der Natur\u201c als eine wichtige Voraussetzung herausgestellt haben, die wertsch\u00e4tzende Handlungen zur Folge haben. Wie kann eine wertsch\u00e4tzende&hellip;","og_url":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/","og_site_name":"W\u00fcrdekompass-Berlin-Britz","article_published_time":"2024-07-29T13:35:07+00:00","article_modified_time":"2024-07-29T13:53:17+00:00","og_image":[{"width":1748,"height":1240,"url":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/wp-content\/uploads\/2024\/07\/Solidaritaet_I.jpg","type":"image\/jpeg"}],"author":"Barbara","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Barbara","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/#article","isPartOf":{"@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/"},"author":{"name":"Barbara","@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/#\/schema\/person\/3350a37c9cd83c4675191c961d7074aa"},"headline":"W\u00fcrde und Solidarit\u00e4t &#8211; Austausch und Diskussion mit Dr. Holger Thiel am 15. April 2024","datePublished":"2024-07-29T13:35:07+00:00","dateModified":"2024-07-29T13:53:17+00:00","mainEntityOfPage":{"@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/"},"wordCount":1350,"commentCount":0,"image":{"@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/wp-content\/uploads\/2024\/07\/Solidaritaet_I.jpg","keywords":["Solidarit\u00e4t","W\u00fcrde"],"articleSection":["Veranstaltung"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/","url":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/","name":"W\u00fcrde und Solidarit\u00e4t - Austausch und Diskussion mit Dr. Holger Thiel am 15. April 2024 - W\u00fcrdekompass-Berlin-Britz","isPartOf":{"@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/#primaryimage"},"image":{"@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/wp-content\/uploads\/2024\/07\/Solidaritaet_I.jpg","datePublished":"2024-07-29T13:35:07+00:00","dateModified":"2024-07-29T13:53:17+00:00","author":{"@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/#\/schema\/person\/3350a37c9cd83c4675191c961d7074aa"},"breadcrumb":{"@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/#primaryimage","url":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/wp-content\/uploads\/2024\/07\/Solidaritaet_I.jpg","contentUrl":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/wp-content\/uploads\/2024\/07\/Solidaritaet_I.jpg","width":1748,"height":1240},{"@type":"BreadcrumbList","@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/2024\/07\/29\/wuerde-und-solidaritaet-austausch-und-diskussion-mit-dr-holger-thiel-am-15-april-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/"},{"@type":"ListItem","position":2,"name":"W\u00fcrde und Solidarit\u00e4t &#8211; Austausch und Diskussion mit Dr. Holger Thiel am 15. April 2024"}]},{"@type":"WebSite","@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/#website","url":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/","name":"W\u00fcrdekompass-Berlin-Britz","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/#\/schema\/person\/3350a37c9cd83c4675191c961d7074aa","name":"Barbara","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/32193af0f2e1388eb6828af0dfdad4af2a8fe7eb79ad44cf5b73e6840c7980ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32193af0f2e1388eb6828af0dfdad4af2a8fe7eb79ad44cf5b73e6840c7980ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32193af0f2e1388eb6828af0dfdad4af2a8fe7eb79ad44cf5b73e6840c7980ed?s=96&d=mm&r=g","caption":"Barbara"},"url":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/author\/barbara\/"}]}},"_links":{"self":[{"href":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/wp-json\/wp\/v2\/posts\/272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/wp-json\/wp\/v2\/comments?post=272"}],"version-history":[{"count":2,"href":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/wp-json\/wp\/v2\/posts\/272\/revisions"}],"predecessor-version":[{"id":278,"href":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/wp-json\/wp\/v2\/posts\/272\/revisions\/278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/wp-json\/wp\/v2\/media\/268"}],"wp:attachment":[{"href":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/wp-json\/wp\/v2\/media?parent=272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/wp-json\/wp\/v2\/categories?post=272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/berlin-britz.xn--wrdekompass-thb.org\/index.php\/wp-json\/wp\/v2\/tags?post=272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}